{"id":1075,"date":"2018-07-10T12:37:13","date_gmt":"2018-07-10T10:37:13","guid":{"rendered":"https:\/\/erboristeriasalute.com\/news\/?p=1075"},"modified":"2022-10-06T17:13:44","modified_gmt":"2022-10-06T15:13:44","slug":"meduse-cosa-fare-o-non-fare-in-caso-di-contatto","status":"publish","type":"post","link":"https:\/\/www.erboristeriasalute.com\/news\/meduse-cosa-fare-o-non-fare-in-caso-di-contatto\/","title":{"rendered":"MEDUSE: COSA FARE O NON FARE IN CASO DI CONTATTO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1075\" class=\"elementor elementor-1075 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39784e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39784e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ccecde5\" data-id=\"ccecde5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9676989 elementor-widget elementor-widget-text-editor\" data-id=\"9676989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chiunque ami nuotare in mare sa che deve fare i conti con <strong>il rischio di spiacevoli incontri con le meduse.<\/strong> <br \/>Si tratta di un\u2019amara realt\u00e0: le meduse stanno aumentando notevolmente di numero negli ultimi anni.<br \/>Questo aumento \u00e8 dovuto ad un tipo di pesca indiscriminata sui nostri mari che ha ridotto in modo drastico i tanti predatori naturali delle meduse. Inoltre, si registra una presenza sempre pi\u00f9 massiccia di un tipo di vegetazione diversificata che pare l\u2019habitat ideale per questi animali, a causa di una vera e propria concimazione innaturale che abbiamo provocato nei fondali dei mari, con fertilizzanti provenienti dai campi coltivati e riversati in acqua.<br \/>Programmando una vacanza al mare dunque, dovremo rassegnarci alla possibilit\u00e0 di avere un contatto ravvicinato con questi animali fastidiosi.<\/p><p><strong>Vediamo allora quali precauzioni adottare in caso di contatto con una medusa.<\/strong><br \/>La causa del \u201cproblema medusa\u201d sarebbero le cnidocisti: le particolari cellule della medusa che una volta a contatto con una qualsiasi parte del nostro corpo, rilascerebbero immediatamente e all\u2019interno della pelle una sostanza urticante. La sensazione \u00e8 molto spiacevole: <strong>si percepisce subito bruciore intenso e, poco dopo, un forte prurito<\/strong>.<br \/>E\u2019 giusto dire che nei nostri mari non esistono, generalmente, meduse in grado di dare problemi diversi da questi spiacevoli sintomi: le dimensioni sono abbastanza ridotte, \u00e8 solitamente trasparente, o di colore lieve che tende al viola.<br \/>Tale specie di medusa, non \u00e8 quasi mai pericolosa.<br \/>Nonostante ci\u00f2, molto dipende, non tanto dalla sostanza che viene a contatto con la nostra pelle, quanto dalla reazione individuale di ogni individuo. <br \/>Pericolo maggiore, si pu\u00f2 verificare nel momento in cui ci si ritrovasse nel bel mezzo di un branco e si riportassero &#8220;punture&#8221; su larga parte del corpo: in questo caso la faccenda potrebbe farsi molto seria.<br \/><strong><br \/>Cosa fare in caso di contatto con una medusa:<\/strong><br \/>La prima cosa che tutti raccomandano \u00e8 quella di non perdere la calma, agitarsi provoca solo il circolo di maggiori quantit\u00e0 di adrenalina, rendendo la respirazione pi\u00f9 difficile, il ch\u00e8 pu\u00f2 rivelarsi molto pericoloso se il tutto accade al largo.<br \/>Una volta giunti sulla spiaggia, la prima cosa da fare \u00e8 verificare che la medusa non abbia lasciato sulla parte interessata parti residue del suo corpo, le quali andrebbero eliminate al pi\u00f9 presto. Non strofinare nulla nella parte interessata dal contatto o si rischierebbe di far penetrare pi\u00f9 in profondit\u00e0 la sostanza urticante.<br \/><strong><br \/>Il miglior metodo<\/strong><br \/>E\u2019 invece opinione sempre pi\u00f9 diffusa che il metodo migliore, di fronte ad una puntura di medusa, sia il Gel Astringente al cloruro di alluminio che, oltre a togliere il prurito che si presenta subito dopo, mitiga anche il bruciore. Antistaminici e cortisone per uso topico, pur potendo avere una loro funzione, hanno tempi di azione lunghi e non risolvono la situazione nell\u2019immediato.<br \/><strong><br \/>Rari casi gravi<\/strong><br \/>Se il soggetto colpito va in stato di semi-coscienza, appare confuso e disorientato, ha difficolt\u00e0 respiratorie, impallidisce, suda in maniera eccessiva e comincia a gonfiarsi in tutto il corpo, \u00e8 altissimo il rischio di uno shock anafilattico: situazione gravissima che, senza un intervento tempestivo, pu\u00f2 portare alla morte in breve tempo.<br \/>La prima cosa da fare \u00e8 sempre chiamare i soccorsi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6129bb9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6129bb9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3853ac42\" data-id=\"3853ac42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19bb12a6 elementor-widget elementor-widget-text-editor\" data-id=\"19bb12a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Seguici sui nostri SOCIAL!<\/h5><p>Approfondimenti, offerte speciali, notizie dal mondo naturale e tanto altro!<br \/> Clicca su &#8220;<strong>MI PIACE<\/strong>&#8221; per essere sempre aggiornato sulle nostre iniziative!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-502b80e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"502b80e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6efc596b\" data-id=\"6efc596b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14926ee6 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"14926ee6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-51175dc\" href=\"https:\/\/www.facebook.com\/NutraLabs-471237786352640\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-facebook\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-51639a2\" href=\"https:\/\/www.instagram.com\/nutralabs\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-instagram\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Chiunque ami nuotare in mare sa che deve fare i conti con il rischio di spiacevoli incontri con le meduse. Si tratta di un\u2019amara realt\u00e0: le meduse stanno aumentando notevolmente di numero negli ultimi anni.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[180,49],"class_list":["post-1075","post","type-post","status-publish","format-standard","hentry","category-salute","tag-meduse","tag-salute"],"_links":{"self":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":0,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}