{"id":2234,"date":"2020-01-09T12:00:02","date_gmt":"2020-01-09T11:00:02","guid":{"rendered":"https:\/\/erboristeriasalute.com\/news\/?p=2234"},"modified":"2022-10-06T17:10:37","modified_gmt":"2022-10-06T15:10:37","slug":"sostenibilita-a-tavola","status":"publish","type":"post","link":"https:\/\/www.erboristeriasalute.com\/news\/sostenibilita-a-tavola\/","title":{"rendered":"SOSTENIBILIT\u00c0 A TAVOLA"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2234\" class=\"elementor elementor-2234 elementor-bc-flex-widget\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d4ff7e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d4ff7e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-903b9d9\" data-id=\"903b9d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d3358f elementor-widget elementor-widget-text-editor\" data-id=\"3d3358f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;alimentazione, come ben sappiamo, \u00e8 uno dei fattori che maggiormente influenzano la nostra salute. <br \/>Ma \u2013 e questo forse \u00e8 un argomento meno noto \u2013 <strong>le scelte alimentari hanno un impatto enorme anche sull&#8217;ambiente.<\/strong> <br \/>La FAO avverte, per esempio, che il settore dell&#8217;allevamento, compresa la coltivazione di vegetali destinati al nutrimento degli animali, \u00e8 responsabile dell&#8217;emissione di enormi quantit\u00e0 di gas serra (colpevoli dei cambiamenti climatici), della maggior parte dello sfruttamento delle terre del pianeta, e rappresenta la principale fonte di inquinamento delle acque. Il trasporto di alimenti da una parte all&#8217;altra del globo contribuisce anch&#8217;esso all&#8217;inquinamento e alle emissioni di CO2. Immense quantit\u00e0 di materiali plastici vengono prodotte, e devono poi essere smaltite, per realizzare gli imballaggi alimentari. Ci sono poi Paesi in cui le colture intensive, realizzate principalmente per soddisfare le richieste del mercato occidentale (banane, olio di palma, quinoa&#8230;), stanno letteralmente distruggendo interi ecosistemi e societ\u00e0 umane a causa dello sfruttamento della terra e del lavoro. E questi sono solo alcuni esempi all&#8217;interno di un quadro estremamente complesso.<\/p><p>\u00c8 necessario e urgente prendere consapevolezza dell&#8217;impatto che la nostra alimentazione ha sull&#8217;ambiente e su molte societ\u00e0 umane, e orientarci con le nostre scelte verso modelli alimentari che siano non solo sani ma anche sostenibili. <br \/><strong>Come fare?<\/strong> <br \/>Un aiuto arriva da Greenpeace: l&#8217;associazione ambientalista ha pubblicato un decalogo di consigli che aiutano a capire quali siano le scelte alimentari pi\u00f9 amiche del clima e del pianeta (il documento originale si pu\u00f2 scaricare qui: <a href=\"https:\/\/storage.googleapis.com\/planet4-italy-stateless\/2019\/11\/a6d03e0b-ecomen%C3%B9_greenpeace.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/storage.googleapis.com\/planet4-italy-stateless\/2019\/11\/a6d03e0b-ecomen%C3%B9_greenpeace.pdf<\/a>). <br \/><br \/>Vediamoli uno per uno.<\/p><p><strong>1. FRUTTA E VERDURA.<\/strong> <br \/>Meglio scegliere quella di stagione, prodotta localmente e biologica.<\/p><p><strong>2. CARNE.<\/strong> <br \/>Il consiglio di Greenpeace \u00e8 di limitarne il consumo a una\/due porzioni a settimana (quantit\u00e0 che, se integrata con le proteine di origine vegetale, \u00e8 perfettamente compatibile con una dieta bilanciata). Bisogna sottolineare che in Italia non esiste l&#8217;obbligo di specificare il metodo di allevamento in etichetta, quindi l&#8217;unico modo per scegliere carne proveniente da allevamenti non intensivi \u2013 che garantiscono un prodotto pi\u00f9 sano, un minor impatto ambientale e un maggior benessere degli animali \u2013 \u00e8 acquistare da produttori che si conoscono direttamente, ad esempio attraverso i gruppi di acquisto solidali (GAS).<\/p><p><strong>3. UOVA.<\/strong> <br \/>Meglio scegliere quelle biologiche, riconoscibili dal fatto che il codice stampato su ogni singolo uovo comincia con il numero \u201c0\u201d. \u201c3\u201d indica galline allevate in gabbia, \u201c2\u201d allevamenti senza gabbie (a terra), ma intensivi e al chiuso, \u201c1\u201d all&#8217;aperto ma pur sempre intensivi. Attenzione: diciture come \u201cprodotto di cascina\u201d o \u201ccome da tradizione\u201d non significano nulla e non danno nessuna informazione sul metodo di allevamento!<\/p><p><strong>4. LATTE E LATTICINI.<\/strong> <br \/>Il consiglio di Greenpeace \u00e8 di limitarne il consumo settimanale a 600 g, privilegiando i prodotti provenienti da allevamenti ecologici. Questo tipo di allevamento infatti garantisce che gli animali siano allevati all&#8217;aperto, con rispetto e senza sofferenze, con un&#8217;alimentazione basata principalmente sul pascolo e sui residui agricoli, e che il terreno utilizzato per la loro alimentazione non sia stato sottratto alla produzione alimentare.<\/p><p><strong>5. PESCE.<\/strong> <br \/>Qui occorre informarsi per imparare a riconoscere il pesce di stagione, locale e pescato in modo artigianale, piuttosto che allevato o pescato con metodi distruttivi.<\/p><p><strong>6. SOTTOCOSTO.<\/strong> <br \/>Massima attenzione ai cibi a basso costo. Spesso comportano sfruttamento dei lavoratori, aste al ribasso sui prezzi e un uso massiccio di erbicidi, insetticidi e fertilizzanti.<\/p><p><strong>7. MODE INSOSTENIBILI.<\/strong> <br \/>Spesso i prodotti esotici, come avocado, banane e quinoa, sono il frutto di monocolture estensive che nei Paesi di origine si espandono a discapito delle foreste e dei diritti umani. Meglio scegliere alternative locali e ugualmente salutari.<\/p><p><strong>8. PROTEINE VEGETALI.<\/strong> <br \/>Sono un&#8217;ottima alternativa alla carne, che permette di ridurne drasticamente il consumo. Anche in questo caso occorre un minimo di informazione per imparare a conoscerle. Le fonti principali di proteine vegetali sono legumi, frutta secca e cereali; se abbinate correttamente (ad es. cereali + legumi) hanno lo stesso valore nutrizionale delle proteine animali.<\/p><p><strong>9. IMBALLAGGI.<\/strong> <br \/>Se possibile \u00e8 sempre meglio acquistare i prodotti sfusi, portando sempre con s\u00e9 la borsa della spesa. Quella della plastica \u00e8 infatti un&#8217;emergenza mondiale.<\/p><p><strong>10. CIBI PROCESSATI.<\/strong> <br \/>Qui pu\u00f2 aiutarci la famosa frase dell&#8217;ambientalista Micheal Pollan: \u201cNon mangiare nulla che tua nonna non riconoscerebbe come cibo\u201d. Infatti il cibo industriale, ultra processato e confezionato, ha spesso un basso valore nutrizionale e non \u00e8 amico dell&#8217;ambiente e della salute. La scelta pi\u00f9 corretta \u00e8 la dieta mediterranea, intesa come un&#8217;alimentazione basata su cereali, legumi e verdura, integrata da un consumo moderato di pesce e carne, con l&#8217;olio d&#8217;oliva come condimento base.<\/p><p>Con le scelte corrette possiamo fare molto sia per la nostra salute che per l&#8217;ambiente; e spesso (la cosa ti stupisce?) i due aspetti vanno di pari passo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20a271a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20a271a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74acfe7e\" data-id=\"74acfe7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40e8a15e elementor-widget elementor-widget-text-editor\" data-id=\"40e8a15e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5>Seguici sui nostri SOCIAL!<\/h5><p>Approfondimenti, offerte speciali, notizie dal mondo naturale e tanto altro!<br \/> Clicca su &#8220;<strong>MI PIACE<\/strong>&#8221; per essere sempre aggiornato sulle nostre iniziative!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79ae18d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79ae18d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ce4f93d\" data-id=\"2ce4f93d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ef7e94a elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"3ef7e94a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-51175dc\" href=\"https:\/\/www.facebook.com\/NutraLabs-471237786352640\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-facebook\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-51639a2\" href=\"https:\/\/www.instagram.com\/nutralabs\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-instagram\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&#8217;alimentazione, come ben sappiamo, \u00e8 uno dei fattori che maggiormente influenzano la nostra salute. Ma \u2013 e questo forse \u00e8 un argomento meno noto \u2013 le scelte alimentari hanno un impatto enorme anche sull&#8217;ambiente. La<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[22,1,338],"tags":[25,292,332,49],"class_list":["post-2234","post","type-post","status-publish","format-standard","hentry","category-alimentazione","category-salute","category-scienza-ambiente","tag-alimentazione","tag-alimentazione-sana","tag-ambiente","tag-salute"],"_links":{"self":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts\/2234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/comments?post=2234"}],"version-history":[{"count":0,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/posts\/2234\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/media?parent=2234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/categories?post=2234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.erboristeriasalute.com\/news\/wp-json\/wp\/v2\/tags?post=2234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}